{"id":10927,"date":"2025-05-30T09:58:16","date_gmt":"2025-05-30T12:58:16","guid":{"rendered":"https:\/\/expresso.estadao.com.br\/sao-paulo\/?p=10927"},"modified":"2025-05-30T09:58:16","modified_gmt":"2025-05-30T12:58:16","slug":"roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo","status":"publish","type":"post","link":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/","title":{"rendered":"Roteiros da Prefeitura revelam novos caminhos para explorar S\u00e3o Paulo"},"content":{"rendered":"<p>Conhecer S\u00e3o Paulo pode ser uma experi\u00eancia diferente a cada dia. A cidade re\u00fane op\u00e7\u00f5es que v\u00e3o da efervesc\u00eancia cultural e gastron\u00f4mica \u00e0 imers\u00e3o por trilhas escondidas na Mata Atl\u00e2ntica.<\/p>\n<p>Para apreciar toda essa diversidade, a Prefeitura oferece programas que disponibilizam guias especializados, tanto para explora\u00e7\u00e3o da natureza como da \u00e1rea urbana, e \u00f4nibus gratuitos para quem quer descobrir os principais pontos da cidade sem gastar com transporte.<\/p>\n<p>Um dos programas que incentiva o turismo urbano \u00e9 o <a href=\"https:\/\/capital.sp.gov.br\/web\/turismo\/w\/menu\/336459\"><em>Vai de Roteiro<\/em><\/a>, com visitas guiadas por regi\u00f5es emblem\u00e1ticas da capital. Atualmente, s\u00e3o 15 roteiros ativos, que passam por locais como a Avenida Paulista, o Mercado Municipal, o bairro da Liberdade, o Tri\u00e2ngulo Hist\u00f3rico e o Museu do Ipiranga, sempre acompanhados por guias de turismo credenciados.<\/p>\n<p>A proposta \u00e9 destacar os marcos hist\u00f3ricos, culturais e urbanos que moldam a cidade, promovendo o turismo como vetor de desenvolvimento nos bairros.<\/p>\n<p>No centro hist\u00f3rico, o passeio pelo Tri\u00e2ngulo SP percorre marcos fundadores da cidade, como o Largo S\u00e3o Bento, o Pateo do Collegio e o Largo S\u00e3o Francisco, reunindo parte essencial da mem\u00f3ria paulistana. J\u00e1 na zona oeste, o roteiro pela Vila Madalena explora um dos bairros mais vibrantes de S\u00e3o Paulo, conhecido por sua intensa vida cultural, grafites, ateli\u00eas, bares e restaurantes.<\/p>\n<p>Outra experi\u00eancia marcante \u00e9 o roteiro pelo tradicional Mercad\u00e3o, inaugurado em 1933 e abrigado em um pr\u00e9dio projetado pelo escrit\u00f3rio de Ramos de Azevedo. Al\u00e9m da arquitetura imponente, o passeio permite um mergulho por diferentes sabores, em um dos principais polos gastron\u00f4micos de S\u00e3o Paulo.<\/p>\n<p><strong>Turistou Tarifa Zero<\/strong><\/p>\n<p>Outra a\u00e7\u00e3o voltada \u00e0 explora\u00e7\u00e3o urbana \u00e9 o <a href=\"https:\/\/capital.sp.gov.br\/w\/programa-turistou-tarifa-zero-incentiva-popula%C3%A7%C3%A3o-a-conhecer-endere%C3%A7os-culturais-gratuitos-da-cidade-aos-domingos#:~:text=Sobre%20o%20Doming%C3%A3o%20Tarifa%20Zero,atividades%20culturais%2C%20esportivas%20e%20religiosas.\"><em>Turistou Tarifa Zero<\/em><\/a>, que sugere passeios completos sem custo, combinando o transporte de \u00f4nibus gratuito que \u00e9 oferecido pela Prefeitura aos domingos. S\u00e3o diversas possibilidades de roteiros, que incluem locais como o Museu Catavento, a Japan House, o Parque Augusta, o \u201cMinhoc\u00e3o\u201d e o Mosteiro de S\u00e3o Bento, entre outros. Nessa a\u00e7\u00e3o n\u00e3o s\u00e3o oferecidos guias de turismo, trata-se de uma sele\u00e7\u00e3o feita pela Prefeitura de locais para explorar de gra\u00e7a.<\/p>\n<p><strong>N\u00fameros da metr\u00f3pole<\/strong><\/p>\n<h5><strong>30,8 <\/strong>mil restaurantes e similares<\/h5>\n<h5><strong>81 <\/strong>tipos de cozinha<\/h5>\n<h5><strong>186 <\/strong>museus e galerias de arte<\/h5>\n<h5><strong>172 <\/strong>teatros e centros culturais<\/h5>\n<div id=\"attachment_10931\" style=\"width: 1120px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-10931\" class=\"wp-image-10931 size-large\" src=\"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54472029575_c526966fbe_6k-1110x740.jpg\" alt=\"\" width=\"1110\" height=\"740\" srcset=\"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54472029575_c526966fbe_6k-1110x740.jpg 1110w, https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54472029575_c526966fbe_6k-450x300.jpg 450w, https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54472029575_c526966fbe_6k-768x512.jpg 768w, https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54472029575_c526966fbe_6k-1536x1024.jpg 1536w, https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54472029575_c526966fbe_6k-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1110px) 100vw, 1110px\" \/><p id=\"caption-attachment-10931\" class=\"wp-caption-text\">Ilha do Boror\u00e9, na Zona Sul<\/p><\/div>\n<p><strong>Natureza<\/strong><\/p>\n<p>Para quem busca natureza e tranquilidade, o Polo de Ecoturismo de S\u00e3o Paulo, na zona sul, revela uma face menos conhecida da metr\u00f3pole. A regi\u00e3o de Parelheiros concentra mais de 400 km\u00b2 de \u00e1reas preservadas, trilhas, cachoeiras, parques naturais e comunidades ind\u00edgenas, em um territ\u00f3rio que ocupa 28% do territ\u00f3rio da capital. \u00c9 um ref\u00fagio com mais de 50 atrativos tur\u00edsticos mapeados, onde o turismo sustent\u00e1vel se alia \u00e0 preserva\u00e7\u00e3o ambiental e \u00e0 valoriza\u00e7\u00e3o cultural.<\/p>\n<p>Os Parques Naturais Municipais (PNM) Jaceguava, Itaim, Varginha e Boror\u00e9 oferecem atividades de lazer, educa\u00e7\u00e3o ambiental e turismo, assim como recebem pesquisadores. Juntos, os quatro parques totalizam mais de 1.500 hectares de \u00e1rea que resguardam importantes fragmentos de vegeta\u00e7\u00e3o nativa.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhecer S\u00e3o Paulo pode ser uma experi\u00eancia diferente a cada dia. A cidade re\u00fane op\u00e7\u00f5es que v\u00e3o da efervesc\u00eancia cultural e gastron\u00f4mica \u00e0 imers\u00e3o por trilhas escondidas na Mata Atl\u00e2ntica. Para apreciar toda essa diversidade, a Prefeitura oferece programas que disponibilizam guias especializados, tanto para explora\u00e7\u00e3o da natureza como da \u00e1rea urbana, e \u00f4nibus gratuitos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[744],"tags":[52,465,1224,252],"class_list":["post-10927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo","tag-prefeitura-de-sao-paulo","tag-turismo","tag-turistou","tag-vai-de-roteiro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>caminhos para explorar S\u00e3o Paulo<\/title>\n<meta name=\"description\" content=\"Passeios guiados, atra\u00e7\u00f5es gratuitas e natureza preservada ampliam as possibilidades de conhecer a cidade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"caminhos para explorar S\u00e3o Paulo\" \/>\n<meta property=\"og:description\" content=\"Passeios guiados, atra\u00e7\u00f5es gratuitas e natureza preservada ampliam as possibilidades de conhecer a cidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Estad\u00e3o Expresso S\u00e3o Paulo\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T12:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fabio_bairros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fabio_bairros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/\",\"url\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/\",\"name\":\"caminhos para explorar S\u00e3o Paulo\",\"isPartOf\":{\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg\",\"datePublished\":\"2025-05-30T12:58:16+00:00\",\"dateModified\":\"2025-05-30T12:58:16+00:00\",\"author\":{\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/#\/schema\/person\/f45f9e313ba8cbe5af9424f387ddef42\"},\"description\":\"Passeios guiados, atra\u00e7\u00f5es gratuitas e natureza preservada ampliam as possibilidades de conhecer a cidade\",\"breadcrumb\":{\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#primaryimage\",\"url\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg\",\"contentUrl\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Parque Natural Itaim, extremo sul de S\u00e3o Paulo - Foto: Ciete Silv\u00e9rio\/Secom\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roteiros da Prefeitura revelam novos caminhos para explorar S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/#website\",\"url\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/\",\"name\":\"Estad\u00e3o Expresso S\u00e3o Paulo\",\"description\":\"Conte\u00fado de presta\u00e7\u00e3o de servi\u00e7o para que os moradores da cidade de S\u00e3o Paulo possam se informar melhor e usar de maneira mais eficaz os servi\u00e7os p\u00fablicos municipais.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/#\/schema\/person\/f45f9e313ba8cbe5af9424f387ddef42\",\"name\":\"fabio_bairros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/expresso.estadao.com.br\/sao-paulo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fbecca90befcfda9505216ce0dc87261326cb6644deb5861e7ab404061c24246?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fbecca90befcfda9505216ce0dc87261326cb6644deb5861e7ab404061c24246?s=96&d=mm&r=g\",\"caption\":\"fabio_bairros\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"caminhos para explorar S\u00e3o Paulo","description":"Passeios guiados, atra\u00e7\u00f5es gratuitas e natureza preservada ampliam as possibilidades de conhecer a cidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/","og_locale":"pt_BR","og_type":"article","og_title":"caminhos para explorar S\u00e3o Paulo","og_description":"Passeios guiados, atra\u00e7\u00f5es gratuitas e natureza preservada ampliam as possibilidades de conhecer a cidade","og_url":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/","og_site_name":"Estad\u00e3o Expresso S\u00e3o Paulo","article_published_time":"2025-05-30T12:58:16+00:00","og_image":[{"width":"","height":"","url":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg","type":"image\/jpeg"}],"author":"fabio_bairros","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fabio_bairros","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/","url":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/","name":"caminhos para explorar S\u00e3o Paulo","isPartOf":{"@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#primaryimage"},"image":{"@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg","datePublished":"2025-05-30T12:58:16+00:00","dateModified":"2025-05-30T12:58:16+00:00","author":{"@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/#\/schema\/person\/f45f9e313ba8cbe5af9424f387ddef42"},"description":"Passeios guiados, atra\u00e7\u00f5es gratuitas e natureza preservada ampliam as possibilidades de conhecer a cidade","breadcrumb":{"@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#primaryimage","url":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg","contentUrl":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-content\/uploads\/2025\/05\/54413478146_ea6efe2471_k-1.jpg","width":2048,"height":1365,"caption":"Parque Natural Itaim, extremo sul de S\u00e3o Paulo - Foto: Ciete Silv\u00e9rio\/Secom"},{"@type":"BreadcrumbList","@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/2025\/05\/30\/roteiros-da-prefeitura-revelam-novos-caminhos-para-explorar-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/expresso.estadao.com.br\/sao-paulo\/"},{"@type":"ListItem","position":2,"name":"Roteiros da Prefeitura revelam novos caminhos para explorar S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/#website","url":"https:\/\/expresso.estadao.com.br\/sao-paulo\/","name":"Estad\u00e3o Expresso S\u00e3o Paulo","description":"Conte\u00fado de presta\u00e7\u00e3o de servi\u00e7o para que os moradores da cidade de S\u00e3o Paulo possam se informar melhor e usar de maneira mais eficaz os servi\u00e7os p\u00fablicos municipais.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expresso.estadao.com.br\/sao-paulo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/#\/schema\/person\/f45f9e313ba8cbe5af9424f387ddef42","name":"fabio_bairros","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/expresso.estadao.com.br\/sao-paulo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fbecca90befcfda9505216ce0dc87261326cb6644deb5861e7ab404061c24246?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fbecca90befcfda9505216ce0dc87261326cb6644deb5861e7ab404061c24246?s=96&d=mm&r=g","caption":"fabio_bairros"}}]}},"_links":{"self":[{"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/posts\/10927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/comments?post=10927"}],"version-history":[{"count":9,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/posts\/10927\/revisions"}],"predecessor-version":[{"id":10939,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/posts\/10927\/revisions\/10939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/media\/10930"}],"wp:attachment":[{"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/media?parent=10927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/categories?post=10927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expresso.estadao.com.br\/sao-paulo\/wp-json\/wp\/v2\/tags?post=10927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}